{"id":4163,"date":"2024-07-22T17:31:14","date_gmt":"2024-07-22T09:31:14","guid":{"rendered":"https:\/\/new.balioceansurf.com\/?page_id=4163"},"modified":"2025-12-28T16:55:34","modified_gmt":"2025-12-28T08:55:34","slug":"booking","status":"publish","type":"page","link":"https:\/\/balioceansurf.com\/fr\/booking\/","title":{"rendered":"R\u00c9SERVATION"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4163\" class=\"elementor elementor-4163\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e37dd47 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e37dd47\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7fb338d sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"7fb338d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5e974cd sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"5e974cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2d0d24 elementor-widget elementor-widget-heading\" data-id=\"c2d0d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Formulaire de R\u00e9servation<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556d3cb elementor-widget elementor-widget-text-editor\" data-id=\"556d3cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Commencez la planification de vos sessions avec ce formulaire \u2014 sans paiement imm\u00e9diat. Pas le temps de tout remplir ? Laissez juste un e-mail ou un num\u00e9ro WhatsApp, on s\u2019occupe du reste.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c11e745 elementor-widget elementor-widget-shortcode\" data-id=\"c11e745\" data-element_type=\"widget\" data-e-type=\"widget\" data-no-translation=\"\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9314-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9314\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/4163#wpcf7-f9314-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9314\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9314-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<style>\n    \/* One item by row *\/\n    .one-item-row-display {\n    display: grid;\n    grid-template-columns: 1fr;\n    gap: 20px;\n    margin-bottom: 20px;\n    }\n\n    \/* Two items by row *\/\n    .two-items-row-display {\n    display: grid;\n    grid-template-columns: repeat(2, 1fr);\n    gap: 20px;\n    margin-bottom: 20px;\n    }\n\n    \/* Three items by row *\/\n    .three-items-row-display {\n    display: grid;\n    grid-template-columns: repeat(3, 1fr);\n    gap: 20px;\n    margin-bottom: 20px;\n    }\n\n    @media only screen and (max-width: 600px) {\n            .two-items-row-display,\n            .three-items-row-display {\n                grid-template-columns: 1fr; \/* One item per row for screens smaller than 600px *\/\n        }\n    }\n.cf7-spinner {\n  width: 32px;\n  height: 32px;\n  border: 3px solid #ddd;\n  border-top: 3px solid #284259;\n  border-radius: 50%;\n  display: inline-block;\n  animation: spin 0.8s linear infinite;\n}\n\n@keyframes spin {\n  to { transform: rotate(360deg); }\n}\n<\/style>\n\n<div class=\"two-items-row-display\">\n    <label>Nom :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Nom*\" value=\"\" type=\"text\" name=\"your-lastname\" \/><\/span>\n    <\/label>\n\n    <label>Pr\u00e9nom :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Pr\u00e9nom*\" value=\"\" type=\"text\" name=\"your-firstname\" \/><\/span>\n    <\/label>\n\n    <label>E-mail :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n    <\/label>\n\n    <label>Num\u00e9ro de t\u00e9l\u00e9phone :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"phone_number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"T\u00e9l\u00e9phone, WhatsApp si possible*\" value=\"\" type=\"tel\" name=\"phone_number\" \/><\/span>\n    <\/label>\n\n    <label>Type de stage :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"stage_type\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"select-surf-program\" aria-invalid=\"false\" name=\"stage_type\"><option value=\"\">&#8212;Please choose an option&#8212;<\/option><option value=\"INITIATION \u2013 1 s\u00e9ance\">INITIATION \u2013 1 s\u00e9ance<\/option><option value=\"MINI GLISSE \u2013 3 s\u00e9ances\">MINI GLISSE \u2013 3 s\u00e9ances<\/option><option value=\"SENSATION \u2013 5 s\u00e9ances\">SENSATION \u2013 5 s\u00e9ances<\/option><option value=\"PASSION \u2013 8 s\u00e9ances\">PASSION \u2013 8 s\u00e9ances<\/option><option value=\"JARDIN DU SURF \u2013 1 s\u00e9ance\">JARDIN DU SURF \u2013 1 s\u00e9ance<\/option><option value=\"SURF COACHING \u2013 Demi journ\u00e9e\">SURF COACHING \u2013 Demi journ\u00e9e<\/option><option value=\"SURF CLUB \u2013 6 mois\">SURF CLUB \u2013 6 mois<\/option><option value=\"SURF CLUB \u2013 12 mois\">SURF CLUB \u2013 12 mois<\/option><\/select><\/span>\n    <\/label>\n\n    <label>Date de d\u00e9but :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"date\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" id=\"input-date-beginning\" min=\"2026-07-15\" aria-invalid=\"false\" placeholder=\"Date de d\u00e9but*\" value=\"\" type=\"date\" name=\"date\" \/><\/span>\n    <\/label>\n<\/div>\n\n<div class=\"three-items-row-display\">\n    <label>Adultes :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"adult_number\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"input-adult-number\" min=\"0\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"number\" name=\"adult_number\" \/><\/span>\n    <\/label>\n\n    <label>Enfants (\u201312 ans) :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"child12_number\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"input-child12-number\" min=\"0\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"number\" name=\"child12_number\" \/><\/span>\n    <\/label>\n\n    <label>Enfants (\u20139 ans) :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"child9_number\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"input-child9-number\" min=\"0\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"number\" name=\"child9_number\" \/><\/span>\n    <\/label>\n<\/div>\n\n<div class=\"two-items-row-display\">\n    <label>Pr\u00e9f\u00e9rence horaire :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"preference\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"pref-period\" aria-invalid=\"false\" name=\"preference\"><option value=\"Pas de pr\u00e9f\u00e9rence\">Pas de pr\u00e9f\u00e9rence<\/option><option value=\"Matin\">Matin<\/option><option value=\"Apr\u00e8s-midi\">Apr\u00e8s-midi<\/option><\/select><\/span>\n    <\/label>\n\n    <label>Niveau de surf :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"level\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"level\"><option value=\"D\u00e9butant\">D\u00e9butant<\/option><option value=\"Interm\u00e9diaire\">Interm\u00e9diaire<\/option><option value=\"Avanc\u00e9\">Avanc\u00e9<\/option><option value=\"Jamais surf\u00e9\">Jamais surf\u00e9<\/option><\/select><\/span>\n    <\/label>\n<\/div>\n\n<div class=\"one-item-row-display\">\n    <label>H\u00e9bergement \u00e0 Bali :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Nom et adresse de votre h\u00e9bergement \u00e0 Bali\" value=\"\" type=\"text\" name=\"address\" \/><\/span>\n    <\/label>\n\n    <label>Commentaire :\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"comment\"><textarea cols=\"40\" rows=\"10\" maxlength=\"200\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"D\u00e9tails de votre demande de r\u00e9servation...\" name=\"comment\"><\/textarea><\/span>\n    <\/label>\n\n    <label>Besoin d'aide ?\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"help_checkbox\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"help_checkbox[]\" value=\"Oui, je souhaite \u00eatre rappel\u00e9 par WhatsApp\" \/><span class=\"wpcf7-list-item-label\">Oui, je souhaite \u00eatre rappel\u00e9 par WhatsApp<\/span><\/label><\/span><\/span><\/span>\n    <\/label>\n        <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"payment_type\" \/>\n        <input class=\"wpcf7-form-control wpcf7-hidden\" id=\"external-id\" value=\"\" type=\"hidden\" name=\"external_id\" \/>\n<\/div>\n<div id=\"cf7-loading\" style=\"display:none; text-align:center; margin-top:16px;\">\n  <span class=\"cf7-spinner\"><\/span>\n  <p id=\"cf7-loading-text\" style=\"font-size:14px; opacity:.7;\">\n    Processing\u2026\n  <\/p>\n<\/div>\n<div class=\"two-items-row-display\">\n    <button type=\"button\" id=\"pay-now-btn\">R\u00e9server<\/button>\n    <button type=\"button\" id=\"quote-only-btn\">Obtenir devis<\/button>\n<\/div>\n\n<div class=\"one-item-row-display\" style=\"margin-top:30px;\">\n    <p style=\"font-weight:600;color:#284259;text-align:center;\" id=\"text-price\"><\/p>\n\n    <p style=\"font-weight:600;color:#284259;font-size:12px;display:none;\" id=\"text-condition\">* Le prix affich\u00e9 est indicatif et inclut les offres et les r\u00e9ductions. Un devis personnalis\u00e9 vous sera envoy\u00e9 pour confirmation.<\/p>\n<\/div>\n\n<div id=\"submit-container\" style=\"display:none;\">\n    <input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Obtenir devis\" \/>\n<\/div>\n\n<!-- Hidden fields for calculation and Email sending, unhide for debug ;)-->\n<div id=\"hiddenContent\" hidden>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"debug\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"debug\" aria-invalid=\"false\" placeholder=\"debug field\" value=\"\" type=\"text\" name=\"debug\" \/><\/span>\n\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"child_number\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"child-number\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"child_number\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"price\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"input-price\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"price\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"price_EUR\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"price-eur\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"price_EUR\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"price_adult\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"price-adult\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"price_adult\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"price_child\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"price-child\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"price_child\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"acompte_IDR\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"ack-IDR\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"acompte_IDR\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"acompte_EUR\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" id=\"ack-EUR\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"acompte_EUR\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"date_pretty_format\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"date-pretty-format\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"date_pretty_format\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"stage_title\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"stage-title\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"stage_title\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"period_pref_ack\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"period-pref-ack\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"period_pref_ack\" \/><\/span>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"discount_msg\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"discount-msg\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"discount_msg\" \/><\/span>\n<\/div>\n\n<script>\n    \/\/ Infos des prix et des r\u00e9ductions pour chaque programme en fonction du nombre de participants\n    const surfPrograms = {\n        \"INITIATION \u2013 1 s\u00e9ance\": { adult_price: 990000, child_price: 820000, discount: [1, 1, 1, 0.9, 0.9, 0.85, 0.85, 0.8] },\n        \"MINI GLISSE \u2013 3 s\u00e9ances\": { adult_price: 2790000, child_price: 2290000, discount: [1, 1, 0.95, 0.9, 0.9, 0.85, 0.85, 0.8] },\n        \"SENSATION \u2013 5 s\u00e9ances\": { adult_price: 4490000, child_price: 3650000, discount: [1, 1, 0.95, 0.85, 0.85, 0.8, 0.8, 0.75] },\n        \"PASSION \u2013 8 s\u00e9ances\": { adult_price: 5990000, child_price: 5390000, discount: [1, 1, 0.95, 0.85, 0.85, 0.8, 0.8, 0.75] },\n    };\n\n    const customCourses = {\n        \"JARDIN DU SURF \u2013 1 s\u00e9ance\": { price: 820000 },\n        \"SURF COACHING \u2013 Demi journ\u00e9e\": { price: 1490000 },\n        \"SURF CLUB \u2013 6 mois\": { price: 5990000 },\n        \"SURF CLUB \u2013 12 mois\": { price: 9490000 },\n    };\n\n    let selectSurfProgram = document.querySelector(\"#select-surf-program\");\n    let inputDateBeginning = document.querySelector(\"#input-date-beginning\");\n    let inputAdultNumber = document.querySelector(\"#input-adult-number\");\n    let inputChild9Number = document.querySelector(\"#input-child9-number\");\n    let inputChild12Number = document.querySelector(\"#input-child12-number\");\n    let textPrice = document.querySelector(\"#text-price\");\n    let prefPeriod = document.querySelector(\"#pref-period\");\n\n    \/\/ Variables permettant d'afficher au moment choisi les informations et\/ou de r\u00e9cup\u00e9rer les infos des champs masqu\u00e9s \u00e0 mettre dans les mails\n    let debug = document.querySelector(\"#debug\");\n    let childNumber = document.querySelector(\"#child-number\");\n    let inputPriceValue = document.querySelector(\"#input-price\");\n    let textCondition = document.querySelector(\"#text-condition\");\n    let prettyDate = document.querySelector(\"#date-pretty-format\");\n    let stageTitle = document.querySelector(\"#stage-title\");\n    let periodPrefAck = document.querySelector(\"#period-pref-ack\");\n    let priceEUR = document.querySelector(\"#price-eur\");\n    let priceAdult = document.querySelector(\"#price-adult\");\n    let priceChild = document.querySelector(\"#price-child\");\n    let ackEUR = document.querySelector(\"#ack-EUR\");\n    let ackIDR = document.querySelector(\"#ack-IDR\");\n    let discountMsg = document.querySelector(\"#discount-msg\");\n\n    \/\/ Listeners pour update en temps r\u00e9el les champs de saisie d'\u00e2ge et le calcul de la tarification en fonction du stage, de date et du nombre de participants\n    selectSurfProgram.addEventListener(\"change\", calculatePrice);\n    inputDateBeginning.addEventListener(\"change\", calculatePrice);\n    inputAdultNumber.addEventListener(\"change\", calculatePrice);\n    inputChild9Number.addEventListener(\"change\", calculatePrice);\n    inputChild12Number.addEventListener(\"change\", calculatePrice);\n\n    \/\/ Autres listeners pour l'update des champs calcul\u00e9s et envoy\u00e9s dans le mail de r\u00e9cap\n    inputDateBeginning.addEventListener(\"change\", updatePrettyDate);\n    selectSurfProgram.addEventListener(\"change\", updateStageTitle);\n    selectSurfProgram.addEventListener(\"change\", updatePrices);\n    prefPeriod.addEventListener(\"change\", updateAckText);\n\n    \/\/ Redirection \u00e0 l'envoi du formulaire & GAnalytics\n    document.addEventListener('wpcf7mailsent', function (event) {\n        if (typeof gtag === 'function') {\n            gtag('event', 'conversion_event_submit_lead_form', {\n            'event_category': 'Form',\n            'event_label': 'Lead Form Submission',\n            'value': 1\n            });\n        }\n    });\n\n    \/\/ Fonction allant r\u00e9cup\u00e9rer en live le taux de change pour faire la conversion IDR->currency\n    const API_URL = 'https:\/\/open.er-api.com\/v6\/latest\/IDR'\n    async function exchangeRateFromIDR(currency) {\n        let response = await fetch(API_URL);\n        let rates = await response.json();\n        let rate = rates.rates[currency];\n        let adjustedRate = rate * 0.97;\n        return adjustedRate;\n    }\n\n    \/\/ Fonction op\u00e9rant la translation 'yyyy-mm-dd' to 'dd Month yyyy'\n    function updatePrettyDate() {\n        \/\/ Cr\u00e9ation du nouvel objet Date \u00e0 partir de la saisie\n        const date = new Date(inputDateBeginning.value);\n\n        \/\/ D\u00e9finition des options pour toLocaleDateString et formattage\n        const options = { day: '2-digit', month: 'long', year: 'numeric' };\n        prettyDate.value = date.toLocaleDateString('fr-FR', options);\n    }\n\n    \/\/ R\u00e9cup\u00e9ration du titre du stage uniquement\n    function updateStageTitle() {\n        stageTitle.value = selectSurfProgram.value.split(\" \u2013 \")[0]\n    }\n\n    function updatePrices() {\n        if (selectSurfProgram.value && surfPrograms[selectSurfProgram.value]) {\n            const data = surfPrograms[selectSurfProgram.value];\n            priceAdult.value = data.adult_price;\n            priceChild.value = data.child_price;\n        } else {\n            priceAdult.value = \"\";\n            priceChild.value = \"\";\n        }\n    }\n\n    function updateAckText() {\n        \/\/ R\u00e9cup\u00e9ration du champs s\u00e9lectionn\u00e9\n        if (prefPeriod.value == \"Matin\") {\n            periodPrefAck.value = \"matin\u00e9e\";\n        } else if (prefPeriod.value == \"Apr\u00e8s-midi\") {\n            periodPrefAck.value = \"apr\u00e8s-midi\";\n        } else {\n            periodPrefAck.value = \"matin\u00e9e\/apr\u00e8s-midi\";\n        }\n    }\n\n    \/\/ Calcul du nombre de jours entre la date actuelle et la date de d\u00e9but du stage (pour potentielle promotion)\n    function verifPromoTempo() {\n        const currentDate = new Date();\n        const todayYear = currentDate.getFullYear();\n        const todayMonth = currentDate.getMonth() + 1;\n        const todayDate = currentDate.getDate();\n\n        const oneDay = 24 * 60 * 60 * 1000;\n        const formattedToday = `${todayYear}-${todayMonth < 10 ? '0' : ''}${todayMonth}-${todayDate < 10 ? '0' : ''}${todayDate}`; \/\/ yyyy-mm-dd\n        const timeDiff = Math.abs(new Date(inputDateBeginning.value) - new Date(formattedToday));\n        const daysDiff = Math.floor(timeDiff \/ oneDay);\n\n        return daysDiff;\n    }\n\n    \/\/ Fonction de calcul du prix en fonction du stage, des participants et de la date de d\u00e9but\n    function calculatePrice() {\n        \/\/ Test sur le type de stage s\u00e9lectionn\u00e9, le nombre de participants et le nombre d'\u00e2ges saisis\n        if (surfPrograms[selectSurfProgram.value] && (inputAdultNumber.value > 0 || inputChild12Number.value > 0 || inputChild9Number.value > 0)) {\n            let program = surfPrograms[selectSurfProgram.value]\n            \/\/ Calcul du prix par participant en fonction de l'\u00e2ge\n            childNumber.value = Number(inputChild12Number.value) + Number(inputChild9Number.value);\n            let totalParticipantNumber = Number(childNumber.value) + Number(inputAdultNumber.value);\n            let totalPrice = program.adult_price*Number(inputAdultNumber.value) + program.child_price*Number(childNumber.value);\n\n            \/\/ Application de la r\u00e9duction sur la nombre de participants\n            let reducePrice = totalPrice;\n            if (totalParticipantNumber <= program.discount.length) {\n                reducePrice = Math.round(totalPrice * program.discount[totalParticipantNumber - 1]);\n            } else {\n                \/\/ Si le nombre de participants d\u00e9passe la taille du tableau, application du dernier taux de r\u00e9duction du tableau\n                reducePrice = Math.round(totalPrice * program.discount[program.discount.length - 1]);\n            }\n\n            \/\/ Application de la r\u00e9duction Tempo de 5% (booking 60 jours avant)\n            if (verifPromoTempo() > 60) {\n                reducePrice = Math.round(reducePrice * 0.95);\n            }\n\n            \/\/ Acompte \u00e0 25% du prix en dessous de 1000\u20ac, et 50% au del\u00e0\n            let ackRate = reducePrice < 10000000 ? 0.25 : 0.5;\n\n            \/\/ Conversion asynchrone IDR->EUR\nconst BUFFER = 0.03; \/\/ bisa kamu jadikan configurable\n\nexchangeRateFromIDR(\"EUR\")\n.then(rate => {\n\n    \/\/ rate sekarang adalah EUR per IDR\n    \/\/ kita butuh IDR per EUR\n    const R = 1 \/ rate;\n\n    const adjustedRate = R * (1 - BUFFER);\n\n    const eurPrice = reducePrice \/ adjustedRate;\n\n    \/\/ clean rounding 2 decimal\n    priceEUR.value = eurPrice.toFixed(2);\n\n    ackEUR.value = (eurPrice * ackRate).toFixed(2);\n});\n\n            reducePrice.value = Math.round(reducePrice.value); \/\/ On arrondi finalement le prix avant de calculer l'acompte\n            ackIDR.value = Math.round(reducePrice * ackRate)\n\n            inputPriceValue.value = reducePrice;\n            textPrice.innerHTML =  \"Le montant de votre r\u00e9servation est de \" + reducePrice.toLocaleString('id-ID') + \"* IDR\";\n            if (reducePrice < totalPrice) {\n                textPrice.innerHTML += `<span style=\"font-style: italic; color:#284259;\"> apr\u00e8s r\u00e9duction, au lieu de <s>${totalPrice} IDR<\/s><\/span>`;\n                discountMsg.value = \"apr\u00e8s r\u00e9duction, au lieu de \" + totalPrice + \" IDR\";\n            } else {\n                discountMsg.value = \"\"\n            }\n\n            \/\/ Affichage du texte avec conditions\n            textCondition.style.display = 'block';\n\n        } else if (customCourses[selectSurfProgram.value]) {\n            textPrice.textContent = \"Nous vous contacterons \u00e0 la r\u00e9ception du formulaire pour vous proposer des tarifs personnalis\u00e9s.\";\n            textCondition.style.display = 'none';\n        } else {\n            \/\/ Reset si aucun programme ne correspond\n            textPrice.textContent = \"\";\n            textCondition.style.display = 'none';\n        }\n    }\n    document.addEventListener('DOMContentLoaded', calculatePrice);\n\n<\/script><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701ccff elementor-widget elementor-widget-shortcode\" data-id=\"701ccff\" data-element_type=\"widget\" data-e-type=\"widget\" data-no-translation=\"\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t<style>.elementor-element-701ccff{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7ba788 elementor-widget elementor-widget-text-editor\" data-id=\"c7ba788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">En envoyant ce formulaire de r\u00e9servation, vous acceptez la <a href=\"https:\/\/balioceansurf.com\/fr\/privacy-policy\/\"><strong>Politique de Confidentialit\u00e9<\/strong><\/a> et les <a href=\"https:\/\/balioceansurf.com\/fr\/terms-and-conditions\/\"><strong>Termes et Conditions<\/strong><\/a> de Bali Ocean Surf.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6dfa2db sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"6dfa2db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-424e14e elementor-section-stretched scheme_bos_dark elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"424e14e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc5e383 sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"fc5e383\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daf84a9 elementor-widget elementor-widget-text-editor\" data-id=\"daf84a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les horaires des cours sont d\u00e9finis selon les mar\u00e9es et disponibilit\u00e9s. Nous t\u00e2cherons de prendre en compte vos pr\u00e9f\u00e9rences dans la mesure du possible. Pour les cas particuliers (groupes, \u00e9v\u00e9nements, etc\u2026), vous pouvez demander \u00e0 \u00eatre rappel\u00e9 pour plus de d\u00e9tails ou d&rsquo;informations.<\/p><p>\u00a0<\/p><p>Les cours sont accessibles \u00e0 tous (d\u00e8s 7 ans), pour les d\u00e9butants, interm\u00e9diaires et confirm\u00e9s.<\/p><p>Les horaires et les lieux de pratique sont variables\u00a0<a href=\"https:\/\/fr.surf-forecast.com\/breaks\/Balian\/forecasts\/latest\/six_day\" target=\"_blank\" rel=\"noopener\">en fonction des mar\u00e9es et de la houle<\/a>\u00a0(conditions de vagues).<\/p><p>La dur\u00e9e des cours est de 2h dont 1h30 dans l\u2019eau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b5cc0 elementor-widget elementor-widget-text-editor\" data-id=\"57b5cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le pr\u00eat du mat\u00e9riel comprend :<\/p><ul class=\"trx_addons_list_custom\"><li>Planches de surf avec leash<\/li><li>Lycra<\/li><li>Legging<\/li><li>Casque<\/li><li>Cr\u00e8me solaire sp\u00e9ciale surf<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee36cc9 elementor-widget elementor-widget-text-editor\" data-id=\"ee36cc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul class=\"trx_addons_list_custom\"><li>Vous \u00eates <strong>couverts<\/strong> lors de toute la dur\u00e9e de l\u2019activit\u00e9<\/li><li>L\u2019encadrement se fait par un moniteur <strong>Fran\u00e7ais<\/strong> dipl\u00f4m\u00e9 <a href=\"https:\/\/isasurf.org\/about-isa\/\"><strong>ISA 1&amp;2<\/strong><\/a><\/li><li>Tarifs indiqu\u00e9s en <strong>US Dollars<\/strong> et <strong>par personne<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf3320e elementor-section-stretched elementor-section-full_width scheme_bos_dark elementor-section-height-default elementor-section-height-default\" data-id=\"cf3320e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34ad2ec sc-mobile_inner_width_none sc_layouts_column sc_layouts_column_align_center sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"34ad2ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d65996 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d65996\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a73b67b sc_layouts_column sc_layouts_column_align_left sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"a73b67b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0abc366 sc_layouts_column sc_layouts_column_align_right sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"0abc366\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93d3777 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"93d3777\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a07927d sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"a07927d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df679c9 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"df679c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffddd58 sc_inner_width_none sc_layouts_column_icons_position_left\" data-id=\"ffddd58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Formulaire de R\u00e9servation Commencez la planification de vos sessions avec ce formulaire&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"class_list":["post-4163","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formulaire de R\u00e9servation - Bali Ocean Surf<\/title>\n<meta name=\"description\" content=\"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/balioceansurf.com\/fr\/booking\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formulaire de R\u00e9servation - Bali Ocean Surf\" \/>\n<meta property=\"og:description\" content=\"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/balioceansurf.com\/fr\/booking\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Ocean Surf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/coursdesurfabali\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T08:55:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ContactPage\"],\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/booking\\\/\",\"url\":\"https:\\\/\\\/balioceansurf.com\\\/booking\\\/\",\"name\":\"Formulaire de R\u00e9servation - Bali Ocean Surf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#website\"},\"datePublished\":\"2024-07-22T09:31:14+00:00\",\"dateModified\":\"2025-12-28T08:55:34+00:00\",\"description\":\"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/booking\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/balioceansurf.com\\\/booking\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/booking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/balioceansurf.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00c9SERVATION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/\",\"name\":\"Bali Ocean Surf\",\"description\":\"\u00c9cole de Surf Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#organization\",\"name\":\"Bali Ocean Surf\",\"url\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Bali Ocean Surf\"},\"image\":{\"@id\":\"https:\\\/\\\/balioceansurf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/coursdesurfabali\",\"https:\\\/\\\/www.instagram.com\\\/balioceansurf\\\/\",\"https:\\\/\\\/www.tripadvisor.fr\\\/Attraction_Review-g297697-d4858501-Reviews-Bali_Ocean_Surf-Kuta_Kuta_District_Bali.html\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfuC4yTURISNuUexgbhfN8w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formulaire de R\u00e9servation - Bali Ocean Surf","description":"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/balioceansurf.com\/fr\/booking\/","og_locale":"fr_FR","og_type":"article","og_title":"Formulaire de R\u00e9servation - Bali Ocean Surf","og_description":"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !","og_url":"https:\/\/balioceansurf.com\/fr\/booking\/","og_site_name":"Bali Ocean Surf","article_publisher":"https:\/\/web.facebook.com\/coursdesurfabali","article_modified_time":"2025-12-28T08:55:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ContactPage"],"@id":"https:\/\/balioceansurf.com\/booking\/","url":"https:\/\/balioceansurf.com\/booking\/","name":"Formulaire de R\u00e9servation - Bali Ocean Surf","isPartOf":{"@id":"https:\/\/balioceansurf.com\/en\/#website"},"datePublished":"2024-07-22T09:31:14+00:00","dateModified":"2025-12-28T08:55:34+00:00","description":"Remplissez le formulaire de r\u00e9servation Bali Ocean Surf, la meilleure \u00c9cole de Surf Fran\u00e7aise de Bali pour une exp\u00e9rience inoubliable !","breadcrumb":{"@id":"https:\/\/balioceansurf.com\/booking\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/balioceansurf.com\/booking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/balioceansurf.com\/booking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/balioceansurf.com\/"},{"@type":"ListItem","position":2,"name":"R\u00c9SERVATION"}]},{"@type":"WebSite","@id":"https:\/\/balioceansurf.com\/en\/#website","url":"https:\/\/balioceansurf.com\/en\/","name":"Bali Ocean Surf","description":"\u00c9cole de Surf Fran\u00e7aise","publisher":{"@id":"https:\/\/balioceansurf.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balioceansurf.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/balioceansurf.com\/en\/#organization","name":"Bali Ocean Surf","url":"https:\/\/balioceansurf.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/balioceansurf.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Bali Ocean Surf"},"image":{"@id":"https:\/\/balioceansurf.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/coursdesurfabali","https:\/\/www.instagram.com\/balioceansurf\/","https:\/\/www.tripadvisor.fr\/Attraction_Review-g297697-d4858501-Reviews-Bali_Ocean_Surf-Kuta_Kuta_District_Bali.html","https:\/\/www.youtube.com\/channel\/UCfuC4yTURISNuUexgbhfN8w"]}]}},"_links":{"self":[{"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/pages\/4163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/comments?post=4163"}],"version-history":[{"count":30,"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/pages\/4163\/revisions"}],"predecessor-version":[{"id":12080,"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/pages\/4163\/revisions\/12080"}],"wp:attachment":[{"href":"https:\/\/balioceansurf.com\/fr\/wp-json\/wp\/v2\/media?parent=4163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}